{"id":2628,"count":15,"description":"","link":"https:\/\/freeflix.pl\/portal\/category\/gwiazdy\/","name":"Gwiazdy","slug":"gwiazdy","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Archiwa Gwiazdy - Freeflix.pl - Filmy online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/freeflix.pl\/portal\/category\/gwiazdy\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archiwa Gwiazdy - Freeflix.pl - Filmy online\" \/>\n<meta property=\"og:url\" content=\"https:\/\/freeflix.pl\/portal\/category\/gwiazdy\/\" \/>\n<meta property=\"og:site_name\" content=\"Freeflix.pl - Filmy online\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/freeflix.pl\/portal\/category\/gwiazdy\/\",\"url\":\"https:\/\/freeflix.pl\/portal\/category\/gwiazdy\/\",\"name\":\"Archiwa Gwiazdy - Freeflix.pl - Filmy online\",\"isPartOf\":{\"@id\":\"https:\/\/freeflix.pl\/portal\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/freeflix.pl\/portal\/category\/gwiazdy\/#breadcrumb\"},\"inLanguage\":\"pl-PL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/freeflix.pl\/portal\/category\/gwiazdy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/freeflix.pl\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gwiazdy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/freeflix.pl\/portal\/#website\",\"url\":\"https:\/\/freeflix.pl\/portal\/\",\"name\":\"Freeflix.pl - Filmy online\",\"description\":\"Darmowe filmy online\",\"publisher\":{\"@id\":\"https:\/\/freeflix.pl\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/freeflix.pl\/portal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/freeflix.pl\/portal\/#organization\",\"name\":\"Freeflix.pl - Filmy online\",\"url\":\"https:\/\/freeflix.pl\/portal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\/\/freeflix.pl\/portal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/freeflix.pl\/portal\/wp-content\/uploads\/2025\/10\/freeflixlogo-1.png\",\"contentUrl\":\"https:\/\/freeflix.pl\/portal\/wp-content\/uploads\/2025\/10\/freeflixlogo-1.png\",\"width\":219,\"height\":46,\"caption\":\"Freeflix.pl - Filmy online\"},\"image\":{\"@id\":\"https:\/\/freeflix.pl\/portal\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archiwa Gwiazdy - Freeflix.pl - Filmy online","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/freeflix.pl\/portal\/category\/gwiazdy\/","og_locale":"pl_PL","og_type":"article","og_title":"Archiwa Gwiazdy - Freeflix.pl - Filmy online","og_url":"https:\/\/freeflix.pl\/portal\/category\/gwiazdy\/","og_site_name":"Freeflix.pl - Filmy online","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/freeflix.pl\/portal\/category\/gwiazdy\/","url":"https:\/\/freeflix.pl\/portal\/category\/gwiazdy\/","name":"Archiwa Gwiazdy - Freeflix.pl - Filmy online","isPartOf":{"@id":"https:\/\/freeflix.pl\/portal\/#website"},"breadcrumb":{"@id":"https:\/\/freeflix.pl\/portal\/category\/gwiazdy\/#breadcrumb"},"inLanguage":"pl-PL"},{"@type":"BreadcrumbList","@id":"https:\/\/freeflix.pl\/portal\/category\/gwiazdy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/freeflix.pl\/portal\/"},{"@type":"ListItem","position":2,"name":"Gwiazdy"}]},{"@type":"WebSite","@id":"https:\/\/freeflix.pl\/portal\/#website","url":"https:\/\/freeflix.pl\/portal\/","name":"Freeflix.pl - Filmy online","description":"Darmowe filmy online","publisher":{"@id":"https:\/\/freeflix.pl\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/freeflix.pl\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/freeflix.pl\/portal\/#organization","name":"Freeflix.pl - Filmy online","url":"https:\/\/freeflix.pl\/portal\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/freeflix.pl\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/freeflix.pl\/portal\/wp-content\/uploads\/2025\/10\/freeflixlogo-1.png","contentUrl":"https:\/\/freeflix.pl\/portal\/wp-content\/uploads\/2025\/10\/freeflixlogo-1.png","width":219,"height":46,"caption":"Freeflix.pl - Filmy online"},"image":{"@id":"https:\/\/freeflix.pl\/portal\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/freeflix.pl\/portal\/wp-json\/wp\/v2\/categories\/2628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/freeflix.pl\/portal\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/freeflix.pl\/portal\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/freeflix.pl\/portal\/wp-json\/wp\/v2\/posts?categories=2628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}